{"id":615881,"date":"2026-05-23T16:10:30","date_gmt":"2026-05-23T13:10:30","guid":{"rendered":"https:\/\/mobiiliabi.ee\/toode\/%d0%ba%d0%b0%d0%bc%d0%b5%d1%80%d0%b0-samsung-a325-a32-4g-set4pcs64mpwide-8mpultrawide-5mpmacro-5mpdepth-%d0%b7%d0%b0%d0%b4%d0%bd%d1%8f%d1%8f-%d0%be%d1%80%d0%b8%d0%b3%d0%b8%d0%bd%d0%b0%d0%bb-u\/"},"modified":"2026-06-07T10:06:31","modified_gmt":"2026-06-07T07:06:31","slug":"%d0%ba%d0%b0%d0%bc%d0%b5%d1%80%d0%b0-samsung-a325-a32-4g-set4pcs64mpwide-8mpultrawide-5mpmacro-5mpdepth-%d0%b7%d0%b0%d0%b4%d0%bd%d1%8f%d1%8f-%d0%be%d1%80%d0%b8%d0%b3%d0%b8%d0%bd%d0%b0%d0%bb-u","status":"publish","type":"product","link":"https:\/\/mobiiliabi.ee\/ru\/toode\/%d0%ba%d0%b0%d0%bc%d0%b5%d1%80%d0%b0-samsung-a325-a32-4g-set4pcs64mpwide-8mpultrawide-5mpmacro-5mpdepth-%d0%b7%d0%b0%d0%b4%d0%bd%d1%8f%d1%8f-%d0%be%d1%80%d0%b8%d0%b3%d0%b8%d0%bd%d0%b0%d0%bb-u\/","title":{"rendered":"\u041a\u0430\u043c\u0435\u0440\u0430 Samsung A325 A32 4G (SET,4pcs)(64MP,Wide\/8MP,Ultrawide\/5MP,Macro\/5MP,Depth \u0437\u0430\u0434\u043d\u044f\u044f \u043e\u0440\u0438\u0433\u0438\u043d\u0430\u043b (used Grade A)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":613764,"template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[2138,2116],"product_tag":[972],"class_list":{"0":"post-615881","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kaameramoodulid-ru","7":"product_cat-osad-ja-komponendid-ru","8":"product_tag-saadaval-pealadu-2-3","10":"first","11":"instock","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/mobiiliabi.ee\/ru\/wp-json\/wp\/v2\/product\/615881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobiiliabi.ee\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mobiiliabi.ee\/ru\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/mobiiliabi.ee\/ru\/wp-json\/wp\/v2\/product\/615881\/revisions"}],"predecessor-version":[{"id":615882,"href":"https:\/\/mobiiliabi.ee\/ru\/wp-json\/wp\/v2\/product\/615881\/revisions\/615882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobiiliabi.ee\/ru\/wp-json\/wp\/v2\/media\/613764"}],"wp:attachment":[{"href":"https:\/\/mobiiliabi.ee\/ru\/wp-json\/wp\/v2\/media?parent=615881"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mobiiliabi.ee\/ru\/wp-json\/wp\/v2\/product_brand?post=615881"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mobiiliabi.ee\/ru\/wp-json\/wp\/v2\/product_cat?post=615881"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mobiiliabi.ee\/ru\/wp-json\/wp\/v2\/product_tag?post=615881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}